{"id":18265,"date":"2021-05-10T10:44:03","date_gmt":"2021-05-10T14:44:03","guid":{"rendered":"https:\/\/rehab-u.com\/?p=18265"},"modified":"2024-06-20T09:08:36","modified_gmt":"2024-06-20T13:08:36","slug":"rehabiliter-lepaule-du-lanceur","status":"publish","type":"post","link":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/","title":{"rendered":"R\u00e9habiliter l&#8217;\u00e9paule du lanceur"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Que l\u2019on parle de r\u00e9habiliter l&#8217;\u00e9paule du lanceur ou que l\u2019on cherche \u00e0 faire de la pr\u00e9vention, l&#8217;\u00e9paule du lanceur a besoin de beaucoup d&#8217;amour. Aime ton \u00e9paule et, esp\u00e9rons-le, elle t\u2019aimera en retour.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si tu veux qu\u2019elle t\u2019aime en retour, tu vas devoir lui donner l&#8217;amour qu&#8217;elle m\u00e9rite, tu sais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Peut-\u00eatre en:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Faisant de fr\u00e9quents gestes r\u00e9fl\u00e9chis;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Assurant une bonne communication;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Passant du temps de qualit\u00e9 ensemble;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Variant le type d&#8217;activit\u00e9s que vous aimez et dont vous b\u00e9n\u00e9ficiez tous les deux<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Restant engag\u00e9;\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Portant attention aux d\u00e9tails, etc.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Ouais, cette rehab d&#8217;\u00e9paule est une histoire d&#8217;amour.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mais soyons s\u00e9rieux. L&#8217;essentiel est qu&#8217;une fois de plus, r\u00e9habiliter l&#8217;\u00e9paule du lanceur tient \u00e0 plus qu&#8217;un travail de rotation externe! Il faut une approche bien \u00e9quilibr\u00e9e.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lorsque l\u2019on examine les exigences de l&#8217;\u00e9paule du lanceur, il existe plusieurs composantes:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Acc\u00e9l\u00e9ration &#8211; Isom\u00e9trique and Concentrique<\/span><\/p>\n<p><span style=\"font-weight: 400;\">D\u00e9c\u00e9l\u00e9ration &#8211; Excentrique<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Et le dernier mais non le moindre, le <\/span><b>timing<\/b><span style=\"font-weight: 400;\">!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cependant, nous voyons g\u00e9n\u00e9ralement 2 choses dans les protocoles de r\u00e9adaptation: la r\u00e9adaptation ax\u00e9e uniquement sur la coiffe des rotateurs et la r\u00e9adaptation qui s&#8217;arr\u00eate \u00e0 isoler la coiffe des rotateurs avec des exercices de rotation externe concentriques.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Maintenant, pourquoi est-ce mauvais, ou \u00e0 tout le moins, sous-optimal? D&#8217;une part, les meilleurs du m\u00e9tier utilisent leurs gros muscles pour faire de gros travaux, ce qui signifie &#8230; pas seulement la coiffe. Deuxi\u00e8mement, la plupart du travail acharn\u00e9 de la coiffe des rotateurs est excentrique. Et troisi\u00e8mement, le <\/span><b>timing<\/b><span style=\"font-weight: 400;\"> est primordial.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ne vous m\u00e9prenez pas, la coiffe des rotateurs est extr\u00eamement importante. Elle doit avoir une force suffisante pour faire son travail correctement. Mais quel est son travail? C\u2019est de garder la t\u00eate hum\u00e9rale centr\u00e9e dans la gl\u00e8ne. Elle doit travailler fort pour \u00abmaintenir la balle de golf sur le tee\u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les <\/span><a href=\"https:\/\/rehab-u.com\/blog\/the-overused-and-misused-rotator-cuff-exercises\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">exercices de rotation externe concentrique<\/span><\/a><span style=\"font-weight: 400;\"> aident-ils \u00e0 accomplir cette t\u00e2che? Tel que mentionn\u00e9 pr\u00e9c\u00e9demment, la coiffe a besoin d&#8217;une force suffisante pour fonctionner correctement. Tr\u00e8s souvent, au d\u00e9but, nous allons devoir r\u00e9activer une coiffe qui est inhib\u00e9e ou simplement faible. Cela fait partie d&#8217;un plan solide. Cependant, un plan solide ne s\u2019arr\u00eate pas l\u00e0, en particulier pour les athl\u00e8tes qui entreprennent des activit\u00e9s qui n\u00e9cessitent des exigences plus \u00e9lev\u00e9es que les personnes qui sont simplement heureuses de ne pas avoir mal en prenant les assiettes pour servir le d\u00eener.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il y a un \u00e9cart important entre les deux, et nous devons combler cet \u00e9cart.<\/span><\/p>\n<p><iframe loading=\"lazy\" title=\"Rehabilitating the throwing shoulder\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/BJloQ3fLyag?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/rehab-u.com\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Tu as aim\u00e9 cette vid\u00e9o?\u00a0 N&#8217;oubies-pas de t&#8217;abonner \u00e0 notre <a href=\"https:\/\/www.youtube.com\/channel\/UCzssi1GnLQpHK-ftlIRIYjw\" target=\"_blank\" rel=\"noopener\">chaine YouTube<\/a>!<\/p>\n<p>&nbsp;<\/p>\n<h2><b>Une analogie de la coiffe des rotateurs<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Un r\u00f4le important de la coiffe est de ralentir la puissante rotation interne et adduction horizontale du bras . Par exemple, le petit rond, qui est une source fr\u00e9quente de sensibilit\u00e9 isol\u00e9e chez les lanceurs, pr\u00e9sente une activit\u00e9 maximale (84% MVIC) pendant la d\u00e9c\u00e9leration (1)<\/span><span style=\"font-weight: 400;\">et la plupart des d\u00e9chirures de la coiffe des rotateurs sont localis\u00e9es au milieu du supra-\u00e9pineux post\u00e9rieur au milieu de l&#8217;infra-\u00e9pineux en cons\u00e9quence de rupture de traction (2).<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><span style=\"font-weight: 400;\"><b>C\u2019est assez simple. Plus on acc\u00e9l\u00e8re, plus on doit d\u00e9c\u00e9l\u00e9rer<\/b>\u00a0<\/span><\/h3>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Pour les joueurs de baseball qui effectuent le mouvement le plus rapide de tous les sports en d\u00e9pla\u00e7ant leur \u00e9paule aussi vite que 7000 \u00b0\/s, on peut comprendre qu&#8217;il y a une force importante \u00e0 absorber. En fait, elle a \u00e9t\u00e9 mesur\u00e9 jusqu&#8217;\u00e0 1,5 fois le poids corporel ou environ 1090N (3).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cela signifie qu&#8217;un autre r\u00f4le important de la coiffe des rotateurs est de pr\u00e9venir la distraction et la subluxation ant\u00e9rieure.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ce concept qui consiste non seulement \u00e0 d\u00e9velopper la force, mais aussi \u00e0 l&#8217;absorber fonctionne comme conduire une voiture. Nous avons autant besoin de la p\u00e9dale d&#8217;acc\u00e9l\u00e9rateur que des freins. Si on ne travaille que sur la force concentrique, c\u2019est comme avoir une Ferrari sans freins! \u00c7a n&#8217;a aucun sens.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si nous avons une Ferrari sans freins, nous avons deux options. L&#8217;option la plus s\u00fbre est d&#8217;aller \u00e0 une vitesse que nous pouvons g\u00e9rer. Par cons\u00e9quent, nous nous d\u00e9placerons plus lentement car notre corps va se prot\u00e9ger \u00e0 tout prix. L&#8217;autre option est d&#8217;\u00e9craser notre voiture; nous nous d\u00e9chirons quelque chose parce que nous n\u2019avons pas la capacit\u00e9 physique de ralentir le mouvement.<a href=\"https:\/\/rehab-u.com\/fr\/courses\/fondamentaux-mobilite\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15536 size-full\" src=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/01\/banner-mobilityfr.jpg\" alt=\"banni\u00e8re formation mobilit\u00e9\" width=\"1020\" height=\"566\" srcset=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/01\/banner-mobilityfr.jpg 1020w, https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/01\/banner-mobilityfr-300x166.jpg 300w, https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/01\/banner-mobilityfr-768x426.jpg 768w, https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/01\/banner-mobilityfr-570x315.jpg 570w, https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/01\/banner-mobilityfr-600x333.jpg 600w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/a><\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Laissons les gros gars faire le gros boulot<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La chose importante \u00e0 comprendre est que 1090N est probablement trop pour la coiffe \u00e0 g\u00e9rer \u00e0 elle seule. La coiffe est compos\u00e9e de petits muscles. Des muscles importants, mais petits. Accepter cette quantit\u00e9 de force est un gros travail. Utiliser les petits muscles pour faire un gros travail &#8230; cela va \u00eatre plus \u00e9prouvant \/ stressant et pas vraiment durable.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J&#8217;aime toujours la r\u00e9f\u00e9rence du Seigneur des Anneaux pour celle-l\u00e0: \u00abpartager la charge\u00bb! Laissons les gros faire le gros boulot!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lorsque nous parlons des gros gars, nous parlons du grand dorsal, du grand rond, du trap\u00e8ze inf\u00e9rieur et du biceps brachii. Les meilleurs lanceurs ont rarement de la douleur principalement \u00e0 l&#8217;\u00e9paule ou au coude. La plupart du temps, c&#8217;est le grand dorsal qui prend le coup, et c&#8217;est en fait une excellente nouvelle. Le grand dorsal est le plus gros muscle du haut du corps et est fortement impliqu\u00e9 \u00e0 la fois dans l&#8217;acc\u00e9l\u00e9ration et la d\u00e9c\u00e9l\u00e9ration. Il n&#8217;est pas surprenant que les joueurs professionnels utilisent leurs lats deux fois plus que les joueurs amateurs. Ils laissent les gros muscles faire les gros travaux, ils sont donc plus efficaces.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le grand rond est le \u201cb\u00e9b\u00e9 lats\u201d alors, tu peux imaginer qu&#8217;il sera impliqu\u00e9 de la m\u00eame mani\u00e8re que ce dernier.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les fibres inf\u00e9rieures du trap\u00e8ze enregistrent leur activit\u00e9 la plus \u00e9lev\u00e9e dans la phase de d\u00e9c\u00e9l\u00e9ration pour contr\u00f4ler la protraction et la rotation vers le haut pendant le lancer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le biceps brachial a un r\u00f4le important, celui de ralentir l&#8217;extension du coude. Cela \u00e9vite les probl\u00e8mes de coude tels que la formation d&#8217;ost\u00e9ophytes par hyperextension du coude.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cependant, le biceps brachial peut devenir hyperactif pour prendre en charge le travail de la coiffe de stabilisation ant\u00e9rieure de l\u2019\u00e9paule. Cela pourrait \u00eatre un signe d&#8217;instabilit\u00e9 de l&#8217;\u00e9paule et est non seulement inefficace (4)<\/span><span style=\"font-weight: 400;\">, mais peut \u00e9galement \u00eatre probl\u00e9matique \u00e0 long terme.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwing.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18251 size-full\" src=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwing.jpg\" alt=\"image lanceur\" width=\"272\" height=\"153\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Travailler de mani\u00e8re <\/span><a href=\"https:\/\/rehab-u.com\/fr\/blog\/les-avantages-des-contractions-excentriques-en-entrainement\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">excentrique<\/span><\/a><span style=\"font-weight: 400;\"> sur ces gros muscles est une grande partie de la construction de l\u2019\u00e9paule \u00e0 l&#8217;\u00e9preuve des balles que nous voulons.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Des exercices tels que le <\/span><i><span style=\"font-weight: 400;\">self-flip and catch<\/span><\/i><span style=\"font-weight: 400;\"> et le <\/span><i><span style=\"font-weight: 400;\">partner reverse throw<\/span><\/i><span style=\"font-weight: 400;\"> vont sp\u00e9cifiquement augmenter la demande sur la coiffe et les muscles scapulaires, ainsi que sur les lats\/grand rond.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Self-flip and catch\" src=\"https:\/\/player.vimeo.com\/video\/547476358?h=ca8ca0cd50&amp;dnt=1&amp;app_id=122963\" width=\"563\" height=\"1000\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><b>ASSURE-TOI DE REGARDER LA VID\u00c9O PRINCIPALE DE L&#8217;ARTICLE POUR VOIR COMMENT CES EXERCICES SONT R\u00c9ALIS\u00c9S<\/b><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Prendre des cours de conduite<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">C\u2019est un bon d\u00e9but pour avoir un moteur puissant dans une voiture \u00e0 l&#8217;\u00e9preuve des balles qui a de bons freins. Cependant, on doit savoir conduire la voiture. Les cours de conduite pour l&#8217;\u00e9paule impliqueront le <\/span><b>timing<\/b><span style=\"font-weight: 400;\">!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La coiffe doit r\u00e9agir \u00e0 de nombreux mouvements, petits et grands, pour \u00abmaintenir la balle de golf sur le tee\u00bb. Cela demande de la pr\u00e9cision. Imagine-la comme les muscles oculaires, qui doivent effectuer des mouvements tr\u00e8s pr\u00e9cis. Il s&#8217;agit d&#8217;appliquer la bonne quantit\u00e9 de force, au bon endroit, au bon moment en r\u00e9ponse \u00e0 un stimulus donn\u00e9.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/rot-cuff.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-18254 size-full aligncenter\" src=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/rot-cuff.jpg\" alt=\"image coiffe\" width=\"291\" height=\"197\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">L&#8217;environnement sportif peut \u00eatre tr\u00e8s chaotique, comme en boxe pour frapper ou en judo pour lancer et attraper un adversaire, ce qui fait de la composante r\u00e9active un facteur important \u00e0 consid\u00e9rer en r\u00e9adaptation.<\/span><\/p>\n<p style=\"text-align: center;\">\n<p><span style=\"font-weight: 400;\">Lancer quelque chose avec une intensit\u00e9 plus faible d&#8217;une mani\u00e8re \u00absemblable mais diff\u00e9rente\u00bb est une excellente introduction aux forces de distraction et au timing qui va avec. C\u2019est comme la premi\u00e8re le\u00e7on de conduite, cela nous \u00abmouille les pieds\u00bb et nous aide \u00e0 gagner en confiance.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#8217;exercice de <\/span><i><span style=\"font-weight: 400;\">medball push<\/span><\/i><span style=\"font-weight: 400;\"> est un excellent moyen de progresser vers les forces de distraction et le timing. Lorsque le medball est rel\u00e2ch\u00e9, la coiffe doit r\u00e9agir de mani\u00e8re appropri\u00e9e afin de servir de ventouse pour maintenir la t\u00eate hum\u00e9rale dans la gl\u00e8ne.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Medball push\" src=\"https:\/\/player.vimeo.com\/video\/547476081?h=a23e1ada2f&amp;dnt=1&amp;app_id=122963\" width=\"563\" height=\"1000\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La coiffe des rotateurs est extr\u00eamement importante, et si les exercices en isolation font partie d&#8217;un plan solide, le plan ne peut pas s&#8217;arr\u00eater l\u00e0. Les petits muscles pr\u00e9cis de la coiffe doivent \u00eatre entra\u00een\u00e9s de cette fa\u00e7on, en gardant \u00e0 l&#8217;esprit le timing. Ils doivent \u00e9galement travailler avec les gros muscles qui font les gros travaux. Partager la charge.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">R\u00e9habiliter l\u2019\u00e9paule du lanceur n\u00e9cessite un plan qui consiste \u00e0 s&#8217;assurer de la force concentrique et isom\u00e9trique suffisante de la coiffe, \u00e0 travailler sur la synchronisation et \u00e0 renforcer la capacit\u00e9 excentrique.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Et n&#8217;oubliez pas que c&#8217;est une histoire d&#8217;amour.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>R\u00e9f\u00e9rences<\/strong><\/p>\n<p>1. Escamilla RF, Andrews JR. Shoulder muscle recruitment patterns and related biomechanics during upper extremity sports. Sports Med Auckl NZ. 2009;39(7):569-590. doi:10.2165\/00007256-200939070-00004<br \/>\n2. Andrews JR, Angelo RL. Shoulder arthroscopy for the throwing athlete. Tech Orthop. 1988;3(1):75-82.<br \/>\n3. Fleisig GS, Andrews JR, Dillman CJ, Escamilla RF. Kinetics of baseball pitching with implications about injury mechanisms. Am J Sports Med. 1995;23(2):233-239. doi:10.1177\/036354659502300218<br \/>\n4. Gowan ID, Jobe FW, Tibone JE, Perry J, Moynes DR. A comparative electromyographic analysis of the shoulder during pitching. Professional versus amateur pitchers. Am J Sports<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><strong><a href=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2020\/11\/ma-profil-blog-150x150.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10634 size-thumbnail\" src=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2020\/11\/ma-profil-blog-150x150.png\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2020\/11\/ma-profil-blog-150x150.png 150w, https:\/\/rehab-u.com\/wp-content\/uploads\/2020\/11\/ma-profil-blog-130x130.png 130w, https:\/\/rehab-u.com\/wp-content\/uploads\/2020\/11\/ma-profil-blog-100x100.png 100w, https:\/\/rehab-u.com\/wp-content\/uploads\/2020\/11\/ma-profil-blog-140x140.png 140w, https:\/\/rehab-u.com\/wp-content\/uploads\/2020\/11\/ma-profil-blog.png 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/strong><\/p>\n<p><strong>Marc-Antoine B\u00e9rub\u00e9<\/strong><\/p>\n<p>en collaboration avec Mai-Linh Dovan M.SC., CAT(C)<\/p>\n<p style=\"margin-top: 0in;\">Marc-Antoine est impliqu\u00e9 dans le baseball depuis de nombreuses ann\u00e9es. Il a jou\u00e9 au sein de la structure de Baseball Qu\u00e9bec, au Northeastern Oklahoma A&amp;M College et \u00e0 l\u2019Universit\u00e9 de Pittsburgh. En 2015, il a \u00e9t\u00e9 s\u00e9lectionn\u00e9 dans le rep\u00eachage de la MLB par les Oakland Athletics. Depuis sa retraite, Marc-Antoine transmet sa passion aux jeunes espoirs en tant qu&#8217;entra\u00eeneur des lanceurs de l&#8217;Acad\u00e9mie Baseball Canada.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Que l\u2019on parle de r\u00e9habiliter l&#8217;\u00e9paule du lanceur ou que l\u2019on cherche \u00e0 faire de la pr\u00e9vention, l&#8217;\u00e9paule du lanceur a besoin de beaucoup d&#8217;amour. Aime ton \u00e9paule et,&#8230;<\/p>\n","protected":false},"author":10,"featured_media":18263,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[356],"tags":[448,511,512],"article_type":[],"class_list":{"0":"post-18265","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-non-classifiee","8":"tag-epaule","9":"tag-coiffe-des-rotateurs","10":"tag-epaule-du-lanceur"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9habiliter l&#039;\u00e9paule du lanceur | BLOGUE Rehab-U<\/title>\n<meta name=\"description\" content=\"Que l\u2019on parle de r\u00e9habiliter l&#039;\u00e9paule du lanceur ou que l\u2019on cherche \u00e0 faire de la pr\u00e9vention, l&#039;\u00e9paule du lanceur a besoin de beaucoup d&#039;amour.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9habiliter l&#039;\u00e9paule du lanceur | BLOGUE Rehab-U\" \/>\n<meta property=\"og:description\" content=\"Que l\u2019on parle de r\u00e9habiliter l&#039;\u00e9paule du lanceur ou que l\u2019on cherche \u00e0 faire de la pr\u00e9vention, l&#039;\u00e9paule du lanceur a besoin de beaucoup d&#039;amour.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/\" \/>\n<meta property=\"og:site_name\" content=\"Rehab-U\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/fr-fr.facebook.com\/RehabUMovementPerformanceTherapy\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/RehabUMovementPerformanceTherapy\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-10T14:44:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-20T13:08:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"566\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mai-Linh Dovan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mai-Linh Dovan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/\"},\"author\":{\"name\":\"Mai-Linh Dovan\",\"@id\":\"https:\/\/rehab-u.com\/fr\/#\/schema\/person\/fc17fc53c0a05bbd81b3c7d52f4d2d49\"},\"headline\":\"R\u00e9habiliter l&#8217;\u00e9paule du lanceur\",\"datePublished\":\"2021-05-10T14:44:03+00:00\",\"dateModified\":\"2024-06-20T13:08:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/\"},\"wordCount\":1793,\"commentCount\":32,\"publisher\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg\",\"keywords\":[\"\u00e9paule\",\"coiffe des rotateurs\",\"\u00e9paule du lanceur\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/\",\"url\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/\",\"name\":\"R\u00e9habiliter l'\u00e9paule du lanceur | BLOGUE Rehab-U\",\"isPartOf\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg\",\"datePublished\":\"2021-05-10T14:44:03+00:00\",\"dateModified\":\"2024-06-20T13:08:36+00:00\",\"description\":\"Que l\u2019on parle de r\u00e9habiliter l'\u00e9paule du lanceur ou que l\u2019on cherche \u00e0 faire de la pr\u00e9vention, l'\u00e9paule du lanceur a besoin de beaucoup d'amour.\",\"breadcrumb\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#primaryimage\",\"url\":\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg\",\"contentUrl\":\"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg\",\"width\":1020,\"height\":566},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/rehab-u.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9habiliter l&#8217;\u00e9paule du lanceur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rehab-u.com\/fr\/#website\",\"url\":\"https:\/\/rehab-u.com\/fr\/\",\"name\":\"Rehab-U\",\"description\":\"Movement &amp; Performance therapy\",\"publisher\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rehab-u.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rehab-u.com\/fr\/#organization\",\"name\":\"Rehab-U | Movement & Performance Therapy\",\"url\":\"https:\/\/rehab-u.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/rehab-u.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/rehab-u.com\/wp-content\/uploads\/2019\/01\/Rehab-U_Favicon.png\",\"contentUrl\":\"https:\/\/rehab-u.com\/wp-content\/uploads\/2019\/01\/Rehab-U_Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Rehab-U | Movement & Performance Therapy\"},\"image\":{\"@id\":\"https:\/\/rehab-u.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/fr-fr.facebook.com\/RehabUMovementPerformanceTherapy\/\",\"https:\/\/www.instagram.com\/mai_rehabu\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/rehab-u.com\/fr\/#\/schema\/person\/fc17fc53c0a05bbd81b3c7d52f4d2d49\",\"name\":\"Mai-Linh Dovan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/rehab-u.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1640420e778c6b5b3b24fdfd5a8033a68b2696d3fafdf51ce63003a746883459?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1640420e778c6b5b3b24fdfd5a8033a68b2696d3fafdf51ce63003a746883459?s=96&d=mm&r=g\",\"caption\":\"Mai-Linh Dovan\"},\"sameAs\":[\"https:\/\/www.rehab-u.com\",\"https:\/\/www.facebook.com\/RehabUMovementPerformanceTherapy\",\"https:\/\/www.instagram.com\/mai_rehabu\",\"https:\/\/www.linkedin.com\/in\/mai-linh-dovan-m-sc-cat-c-34a036186\",\"https:\/\/www.youtube.com\/channel\/UCzssi1GnLQpHK-ftlIRIYjw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9habiliter l'\u00e9paule du lanceur | BLOGUE Rehab-U","description":"Que l\u2019on parle de r\u00e9habiliter l'\u00e9paule du lanceur ou que l\u2019on cherche \u00e0 faire de la pr\u00e9vention, l'\u00e9paule du lanceur a besoin de beaucoup d'amour.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9habiliter l'\u00e9paule du lanceur | BLOGUE Rehab-U","og_description":"Que l\u2019on parle de r\u00e9habiliter l'\u00e9paule du lanceur ou que l\u2019on cherche \u00e0 faire de la pr\u00e9vention, l'\u00e9paule du lanceur a besoin de beaucoup d'amour.","og_url":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/","og_site_name":"Rehab-U","article_publisher":"https:\/\/fr-fr.facebook.com\/RehabUMovementPerformanceTherapy\/","article_author":"https:\/\/www.facebook.com\/RehabUMovementPerformanceTherapy","article_published_time":"2021-05-10T14:44:03+00:00","article_modified_time":"2024-06-20T13:08:36+00:00","og_image":[{"width":1020,"height":566,"url":"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg","type":"image\/jpeg"}],"author":"Mai-Linh Dovan","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Mai-Linh Dovan","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#article","isPartOf":{"@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/"},"author":{"name":"Mai-Linh Dovan","@id":"https:\/\/rehab-u.com\/fr\/#\/schema\/person\/fc17fc53c0a05bbd81b3c7d52f4d2d49"},"headline":"R\u00e9habiliter l&#8217;\u00e9paule du lanceur","datePublished":"2021-05-10T14:44:03+00:00","dateModified":"2024-06-20T13:08:36+00:00","mainEntityOfPage":{"@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/"},"wordCount":1793,"commentCount":32,"publisher":{"@id":"https:\/\/rehab-u.com\/fr\/#organization"},"image":{"@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#primaryimage"},"thumbnailUrl":"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg","keywords":["\u00e9paule","coiffe des rotateurs","\u00e9paule du lanceur"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/","url":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/","name":"R\u00e9habiliter l'\u00e9paule du lanceur | BLOGUE Rehab-U","isPartOf":{"@id":"https:\/\/rehab-u.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#primaryimage"},"image":{"@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#primaryimage"},"thumbnailUrl":"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg","datePublished":"2021-05-10T14:44:03+00:00","dateModified":"2024-06-20T13:08:36+00:00","description":"Que l\u2019on parle de r\u00e9habiliter l'\u00e9paule du lanceur ou que l\u2019on cherche \u00e0 faire de la pr\u00e9vention, l'\u00e9paule du lanceur a besoin de beaucoup d'amour.","breadcrumb":{"@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#primaryimage","url":"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg","contentUrl":"https:\/\/rehab-u.com\/wp-content\/uploads\/2021\/05\/throwingshoulder-thumbnail.jpg","width":1020,"height":566},{"@type":"BreadcrumbList","@id":"https:\/\/rehab-u.com\/fr\/rehabiliter-lepaule-du-lanceur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rehab-u.com\/fr\/"},{"@type":"ListItem","position":2,"name":"R\u00e9habiliter l&#8217;\u00e9paule du lanceur"}]},{"@type":"WebSite","@id":"https:\/\/rehab-u.com\/fr\/#website","url":"https:\/\/rehab-u.com\/fr\/","name":"Rehab-U","description":"Movement &amp; Performance therapy","publisher":{"@id":"https:\/\/rehab-u.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rehab-u.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rehab-u.com\/fr\/#organization","name":"Rehab-U | Movement & Performance Therapy","url":"https:\/\/rehab-u.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rehab-u.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/rehab-u.com\/wp-content\/uploads\/2019\/01\/Rehab-U_Favicon.png","contentUrl":"https:\/\/rehab-u.com\/wp-content\/uploads\/2019\/01\/Rehab-U_Favicon.png","width":512,"height":512,"caption":"Rehab-U | Movement & Performance Therapy"},"image":{"@id":"https:\/\/rehab-u.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/fr-fr.facebook.com\/RehabUMovementPerformanceTherapy\/","https:\/\/www.instagram.com\/mai_rehabu\/"]},{"@type":"Person","@id":"https:\/\/rehab-u.com\/fr\/#\/schema\/person\/fc17fc53c0a05bbd81b3c7d52f4d2d49","name":"Mai-Linh Dovan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rehab-u.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1640420e778c6b5b3b24fdfd5a8033a68b2696d3fafdf51ce63003a746883459?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1640420e778c6b5b3b24fdfd5a8033a68b2696d3fafdf51ce63003a746883459?s=96&d=mm&r=g","caption":"Mai-Linh Dovan"},"sameAs":["https:\/\/www.rehab-u.com","https:\/\/www.facebook.com\/RehabUMovementPerformanceTherapy","https:\/\/www.instagram.com\/mai_rehabu","https:\/\/www.linkedin.com\/in\/mai-linh-dovan-m-sc-cat-c-34a036186","https:\/\/www.youtube.com\/channel\/UCzssi1GnLQpHK-ftlIRIYjw"]}]}},"_links":{"self":[{"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/posts\/18265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/comments?post=18265"}],"version-history":[{"count":0,"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/posts\/18265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/media\/18263"}],"wp:attachment":[{"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/media?parent=18265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/categories?post=18265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/tags?post=18265"},{"taxonomy":"article_type","embeddable":true,"href":"https:\/\/rehab-u.com\/fr\/wp-json\/wp\/v2\/article_type?post=18265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}